{"id":5,"count":4,"description":"","link":"https:\/\/demo.realchoice.io\/demo27\/category\/real-estate\/","name":"Real Estate","slug":"real-estate","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/demo.realchoice.io\/demo27\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.realchoice.io\/demo27\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demo.realchoice.io\/demo27\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/demo.realchoice.io\/demo27\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}