{"id":1,"count":1,"description":"","link":"https:\/\/demo.realchoice.io\/demo21\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/demo.realchoice.io\/demo21\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.realchoice.io\/demo21\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demo.realchoice.io\/demo21\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/demo.realchoice.io\/demo21\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}